{"id":7041,"date":"2018-10-02T20:35:13","date_gmt":"2018-10-02T20:35:13","guid":{"rendered":"http:\/\/www.andacolloconectado.cl\/?p=7041"},"modified":"2018-10-02T20:35:13","modified_gmt":"2018-10-02T20:35:13","slug":"onemi-decreta-alerta-verde-temprana-preventiva-por-fiesta-chica-de-andacollo","status":"publish","type":"post","link":"https:\/\/www.andacolloconectado.cl\/index.php\/onemi-decreta-alerta-verde-temprana-preventiva-por-fiesta-chica-de-andacollo\/","title":{"rendered":"ONEMI decreta Alerta Verde Temprana Preventiva por Fiesta Chica de Andacollo"},"content":{"rendered":"<p>Esta medida se une al Plan de Contingencia programado por diversos organismos locales, como Protecci\u00f3n Civil del Municipio de Andacollo y Servicios de Emergencia, todo esto en miras a que la celebraci\u00f3n dedicada a Nuestra Se\u00f1ora del Rosario se desarrolle con la mayor normalidad posible.<\/p>\n<p>Con motivo de la celebraci\u00f3n de la Fiesta Religiosa en Honor a Nuestra Se\u00f1ora de Andacollo, que tendr\u00e1 lugar este fin de semana, la Oficina Nacional de Emergencia (ONEMI) ha declarado la Alerta Verde Temprana Preventiva dentro de la comuna, debido al aumento de vulnerabilidad y riesgo que traer\u00e1 la llegada de turistas y peregrinos a la zona, los cuales se estiman superar\u00e1n las 100.000 personas.<\/p>\n<p>Esta medida se extender\u00e1 desde el viernes 5 de octubre hasta el martes 9 de octubre, con el objetivo crear un estado de reforzamiento de las condiciones de vigilancia, por medio del monitoreo permanente de posibles situaciones de amenaza. Esta instancia primaria permite coordinar y activar el Sistema de Protecci\u00f3n Civil en caso de cualquier situaci\u00f3n de emergencia que pueda empa\u00f1ar el desarrollo de la tambi\u00e9n llamada \u201cFiesta Chica\u201d.<\/p>\n<p>Cursos de Acci\u00f3n y Amplitud de Alerta<br \/>\nParticipan de esta Alerta Verde Temprana Preventiva la Intendencia de la regi\u00f3n de Coquimbo, Comit\u00e9 de Operaciones de Emergencia Regional, Comit\u00e9 Regional de Protecci\u00f3n Civil, Gobernaci\u00f3n Provincial de Elqui, Direcciones Provinciales y Comunales de Protecci\u00f3n Civil, Secretar\u00eda Regional Ministerial (SEREMI) de Salud, SEREMI de Energ\u00eda, SEREMI de Agricultura, SEREMI de Electricidad y Combustibles, Superintendencia de Servicios Sanitarios, Carabineros de Chile, Polic\u00eda de Investigaciones (PDI), Servicio de Atenci\u00f3n M\u00e9dica de Urgencia (SAMU), Bomberos, Cruz Roja, Corporaci\u00f3n Nacional Forestal (CONAF), empresas concesionarias de servicios b\u00e1sicos y otros organismos de actuar pertinente.<\/p>\n<p>Todas estas instituciones actuar\u00e1n, durante los d\u00edas que dure la Fiesta, difundiendo las implicancias de la Alerta Verde Temprana Preventiva, activando preventivamente los Comit\u00e9s de Operaciones de Emergencia mediante el correcto ajuste de enlaces de coordinaci\u00f3n y planificaci\u00f3n, vigilancia permanente de puntos cr\u00edticos, detecci\u00f3n de zonas de riesgo y vulnerabilidad, realizaci\u00f3n de mantenciones urbanas para disminuir puntos de vulnerabilidad y la elaboraci\u00f3n de planes de contingencia y coordinaci\u00f3n con servicios de emergencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta medida se une al Plan de Contingencia programado por diversos organismos locales, como Protecci\u00f3n Civil del Municipio de Andacollo y Servicios de Emergencia, todo esto en miras a que la celebraci\u00f3n dedicada a Nuestra Se\u00f1ora del Rosario se desarrolle con la mayor normalidad posible. Con motivo de la celebraci\u00f3n de la Fiesta Religiosa en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[1913],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/posts\/7041"}],"collection":[{"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/comments?post=7041"}],"version-history":[{"count":2,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/posts\/7041\/revisions"}],"predecessor-version":[{"id":7048,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/posts\/7041\/revisions\/7048"}],"wp:attachment":[{"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/media?parent=7041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/categories?post=7041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.andacolloconectado.cl\/index.php\/wp-json\/wp\/v2\/tags?post=7041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}